{"id":1121,"date":"2019-01-21T15:18:05","date_gmt":"2019-01-21T14:18:05","guid":{"rendered":"https:\/\/www.hotelliberty.top\/descubre\/"},"modified":"2025-11-04T11:59:20","modified_gmt":"2025-11-04T10:59:20","slug":"descubre","status":"publish","type":"post","link":"https:\/\/www.hotelliberty.top\/it\/scopri\/","title":{"rendered":"Scopri"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5502f-d4adfe12d776f6e98796f524fb03f6d2\">\n.flex_column.av-5502f-d4adfe12d776f6e98796f524fb03f6d2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-5502f-d4adfe12d776f6e98796f524fb03f6d2 av_one_full  avia-builder-el-0  el_before_av_one_full  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jr7okjw2-6b0a8ba326bb34b3706da11a2f230d04\">\n.avia-image-container.av-jr7okjw2-6b0a8ba326bb34b3706da11a2f230d04 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-jr7okjw2-6b0a8ba326bb34b3706da11a2f230d04 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-jr7okjw2-6b0a8ba326bb34b3706da11a2f230d04 av-styling- avia-align-center  avia-builder-el-1  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-1207 avia-img-lazy-loading-not-1207 avia_image ' src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/liberty-576x684.jpg\" alt='' title='liberty'  height=\"684\" width=\"576\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-17h0mf-45f1ec79c25e85c5d063d12df589fe9b\">\n.flex_column.av-17h0mf-45f1ec79c25e85c5d063d12df589fe9b{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-17h0mf-45f1ec79c25e85c5d063d12df589fe9b av_one_full  avia-builder-el-2  el_after_av_one_full  el_before_av_one_half  first flex_column_div av-zero-column-padding  column-top-margin'     ><section  class='av_textblock_section av-115tlz-4d563ef8128c14961ed3204134556322 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><h1 style=\"text-align: center;\">SCOPRI L&#8217;HOTEL<\/h1>\n<\/div><\/section><br \/>\n<div  class='hr av-vgqw7-6a8b63bb53e319001eb1bf0f0acad363 hr-default  avia-builder-el-4  el_after_av_textblock  avia-builder-el-last '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div><\/p>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-pdz4f-a186e2930b7184357f2a4a73b39e589b\">\n.flex_column.av-pdz4f-a186e2930b7184357f2a4a73b39e589b{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-pdz4f-a186e2930b7184357f2a4a73b39e589b av_one_half  avia-builder-el-5  el_after_av_one_full  el_before_av_one_half  first flex_column_div av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jr7ol0pz-e070294f1d1ea2d4ff1cc04678528ede\">\n#top .avia-gallery.av-jr7ol0pz-e070294f1d1ea2d4ff1cc04678528ede .avia-gallery-thumb a{\nwidth:50%;\n}\n<\/style>\n<div  class='avia-gallery av-jr7ol0pz-e070294f1d1ea2d4ff1cc04678528ede avia_animate_when_visible  avia-builder-el-6  el_before_av_button_big  avia-builder-el-no-sibling  avia_lazyload av-slideshow-ui av-loop-manual-endless av-control-hidden av-navigate-arrows hover-effect av-control-hidden avia-gallery-animate avia-gallery-1'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><meta itemprop=\"contentURL\" content=\"https:\/\/www.hotelliberty.top\/it\/scopri\/\"><a class='avia-gallery-big fakeLightbox lightbox avia-gallery-big-crop-thumb ' href=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3.jpg\" data-srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3.jpg 1024w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3-300x225.jpg 300w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3-768x576.jpg 768w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\"  data-onclick='1' title='familiare3' ><span class='avia-gallery-big-inner'  itemprop=\"thumbnailUrl\" ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1205 avia-img-lazy-loading-not-1205\"  width=\"495\" height=\"400\" src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3-495x400.jpg\" title='familiare3' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3-495x400.jpg 495w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3-845x684.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/span><\/a><div class='avia-gallery-thumb'><a href=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3.jpg\" data-srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3.jpg 1024w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3-300x225.jpg 300w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3-768x576.jpg 768w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3-495x400.jpg' class='first_thumb lightbox ' data-onclick='1' title='familiare3'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1205 avia-img-lazy-loading-not-1205\"   src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3-845x684.jpg\" width=\"845\" height=\"684\"  title='familiare3' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3-845x684.jpg 845w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3-495x400.jpg 495w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1205 avia-img-lazy-loading-1205\"  width=\"495\" height=\"400\" src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3-495x400.jpg\" title='familiare3' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3-495x400.jpg 495w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare3-845x684.jpg 845w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/div><\/a><a href=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale.jpg\" data-srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale.jpg 1024w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale-300x225.jpg 300w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale-768x576.jpg 768w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale-495x400.jpg' class='lightbox ' data-onclick='2' title='matrimoniale'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1209 avia-img-lazy-loading-not-1209\"   src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale-845x684.jpg\" width=\"845\" height=\"684\"  title='matrimoniale' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale-845x684.jpg 845w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale-495x400.jpg 495w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1209 avia-img-lazy-loading-1209\"  width=\"495\" height=\"400\" src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale-495x400.jpg\" title='matrimoniale' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale-495x400.jpg 495w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale-845x684.jpg 845w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/div><\/a><a href=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale2.jpg\" data-srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale2.jpg 1024w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale2-300x225.jpg 300w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale2-768x576.jpg 768w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale2-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale2-495x400.jpg' class='first_thumb lightbox ' data-onclick='3' title='matrimoniale2'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1211 avia-img-lazy-loading-not-1211\"   src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale2-845x684.jpg\" width=\"845\" height=\"684\"  title='matrimoniale2' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale2-845x684.jpg 845w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale2-495x400.jpg 495w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1211 avia-img-lazy-loading-1211\"  width=\"495\" height=\"400\" src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale2-495x400.jpg\" title='matrimoniale2' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale2-495x400.jpg 495w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale2-845x684.jpg 845w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/div><\/a><a href=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale3.jpg\" data-srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale3.jpg 1024w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale3-300x225.jpg 300w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale3-768x576.jpg 768w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale3-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale3-495x400.jpg' class='lightbox ' data-onclick='4' title='matrimoniale3'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1213 avia-img-lazy-loading-not-1213\"   src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale3-845x684.jpg\" width=\"845\" height=\"684\"  title='matrimoniale3' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale3-845x684.jpg 845w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale3-495x400.jpg 495w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1213 avia-img-lazy-loading-1213\"  width=\"495\" height=\"400\" src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale3-495x400.jpg\" title='matrimoniale3' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale3-495x400.jpg 495w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/matrimoniale3-845x684.jpg 845w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/div><\/a><a href=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/salone.jpg\" data-srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/salone.jpg 1024w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/salone-300x225.jpg 300w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/salone-768x576.jpg 768w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/salone-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/salone-495x400.jpg' class='first_thumb lightbox ' data-onclick='5' title='salone'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1215 avia-img-lazy-loading-not-1215\"   src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/salone-845x684.jpg\" width=\"845\" height=\"684\"  title='salone' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/salone-845x684.jpg 845w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/salone-495x400.jpg 495w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1215 avia-img-lazy-loading-1215\"  width=\"495\" height=\"400\" src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/salone-495x400.jpg\" title='salone' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/salone-495x400.jpg 495w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/salone-845x684.jpg 845w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/div><\/a><a href=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/singola.jpg\" data-srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/singola.jpg 1024w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/singola-300x225.jpg 300w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/singola-768x576.jpg 768w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/singola-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/singola-495x400.jpg' class='lightbox ' data-onclick='6' title='singola'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1217 avia-img-lazy-loading-not-1217\"   src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/singola-845x684.jpg\" width=\"845\" height=\"684\"  title='singola' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/singola-845x684.jpg 845w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/singola-495x400.jpg 495w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1217 avia-img-lazy-loading-1217\"  width=\"495\" height=\"400\" src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/singola-495x400.jpg\" title='singola' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/singola-495x400.jpg 495w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/singola-845x684.jpg 845w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/div><\/a><a href=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla.jpg\" data-srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla.jpg 1024w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla-300x225.jpg 300w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla-768x576.jpg 768w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla-495x400.jpg' class='first_thumb lightbox ' data-onclick='7' title='tripla'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1219 avia-img-lazy-loading-not-1219\"   src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla-845x684.jpg\" width=\"845\" height=\"684\"  title='tripla' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla-845x684.jpg 845w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla-495x400.jpg 495w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1219 avia-img-lazy-loading-1219\"  width=\"495\" height=\"400\" src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla-495x400.jpg\" title='tripla' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla-495x400.jpg 495w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla-845x684.jpg 845w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/div><\/a><a href=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla2.jpg\" data-srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla2.jpg 1024w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla2-300x225.jpg 300w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla2-768x576.jpg 768w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla2-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla2-495x400.jpg' class='lightbox ' data-onclick='8' title='tripla2'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1221 avia-img-lazy-loading-not-1221\"   src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla2-845x684.jpg\" width=\"845\" height=\"684\"  title='tripla2' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla2-845x684.jpg 845w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla2-495x400.jpg 495w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1221 avia-img-lazy-loading-1221\"  width=\"495\" height=\"400\" src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla2-495x400.jpg\" title='tripla2' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla2-495x400.jpg 495w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/tripla2-845x684.jpg 845w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/div><\/a><a href=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare.jpg\" data-srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare.jpg 1024w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare-300x225.jpg 300w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare-768x576.jpg 768w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare-495x400.jpg' class='first_thumb lightbox ' data-onclick='9' title='familiare'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1201 avia-img-lazy-loading-not-1201\"   src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare-845x684.jpg\" width=\"845\" height=\"684\"  title='familiare' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare-845x684.jpg 845w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare-495x400.jpg 495w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1201 avia-img-lazy-loading-1201\"  width=\"495\" height=\"400\" src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare-495x400.jpg\" title='familiare' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare-495x400.jpg 495w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/familiare-845x684.jpg 845w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/div><\/a><a href=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione2.jpg\" data-srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione2.jpg 1024w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione2-300x225.jpg 300w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione2-768x576.jpg 768w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione2-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione2-495x400.jpg' class='lightbox ' data-onclick='10' title='colazione2'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1199 avia-img-lazy-loading-not-1199\"   src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione2-845x684.jpg\" width=\"845\" height=\"684\"  title='colazione2' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione2-845x684.jpg 845w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione2-495x400.jpg 495w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1199 avia-img-lazy-loading-1199\"  width=\"495\" height=\"400\" src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione2-495x400.jpg\" title='colazione2' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione2-495x400.jpg 495w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione2-845x684.jpg 845w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/div><\/a><a href=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione.jpg\" data-srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione.jpg 1024w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione-300x225.jpg 300w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione-768x576.jpg 768w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione-495x400.jpg' class='first_thumb lightbox ' data-onclick='11' title='colazione'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1197 avia-img-lazy-loading-not-1197\"   src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione-845x684.jpg\" width=\"845\" height=\"684\"  title='colazione' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione-845x684.jpg 845w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione-495x400.jpg 495w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1197 avia-img-lazy-loading-1197\"  width=\"495\" height=\"400\" src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione-495x400.jpg\" title='colazione' alt='' srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione-495x400.jpg 495w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/colazione-845x684.jpg 845w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/div><\/a><a href=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/amenities.jpg\" data-srcset=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/amenities.jpg 840w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/amenities-300x274.jpg 300w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/amenities-768x702.jpg 768w, https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/amenities-705x645.jpg 705w\" data-sizes=\"(max-width: 840px) 100vw, 840px\" data-rel='gallery-1' data-prev-img='https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/amenities-495x400.jpg' class='lightbox ' data-onclick='12' title='amenities'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-1191 avia-img-lazy-loading-not-1191\"   src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/amenities-840x684.jpg\" width=\"840\" height=\"684\"  title='amenities' alt='' \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-1191 avia-img-lazy-loading-1191\"  width=\"495\" height=\"400\" src=\"https:\/\/www.hotelliberty.top\/wp-content\/uploads\/2025\/11\/amenities-495x400.jpg\" title='amenities' alt='' \/><\/div><\/a><\/div><\/div><br \/>\n<div  class='avia-button-wrap avia-button-center  avia-builder-el-7  el_after_av_gallery  avia-builder-el-last '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l20xb-6b97bd613e875dec6b4aceaf8b6335d1\">\n#top #wrap_all .avia-button.av-l20xb-6b97bd613e875dec6b4aceaf8b6335d1:hover{\ncolor:white;\ntransition:all 0.4s ease-in-out;\n}\n<\/style>\n<a href='https:\/\/www.hotelliberty.top\/prenota' class='avia-color-theme-color avia-font-color-theme-color avia-button avia-button-fullwidth av-l20xb-6b97bd613e875dec6b4aceaf8b6335d1 avia-icon_select-yes-left-icon avia-color-theme-color'   aria-label=\"Prenota Adesso!\"><span class='avia_button_icon avia_button_icon_left' aria-hidden='true' data-av_icon='\ue85b' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >Prenota Adesso!<\/span><span class='avia_button_background avia-button avia-button-fullwidth avia-color-theme-color-subtle'><\/span><\/a><\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-f8d33-70a75adbf8c1706c1ef022d7e7cd112b\">\n.flex_column.av-f8d33-70a75adbf8c1706c1ef022d7e7cd112b{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-f8d33-70a75adbf8c1706c1ef022d7e7cd112b av_one_half  avia-builder-el-8  el_after_av_one_half  avia-builder-el-last  flex_column_div av-zero-column-padding  column-top-margin'     ><section  class='av_textblock_section av-jr7oluc7-58bc173e768c3498f310d18e451b7f65 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><h3>Descrizione<\/h3>\n<p>Immerso in un incantevole giardino fiorito affacciato sul Mar Ligure e situato a soli 600 metri dal Teatro Ariston, l&#8217;Hotel Liberty accoglie gli ospiti con camere dotate di connessione WiFi gratuita.<\/p>\n<p>Le sistemazioni, ricavate in una villa storica del 19\u00b0 secolo, sono arredate in stile tradizionale e offrono comfort moderni come TV LCD e bagno privato con asciugacapelli. La maggior parte delle camere \u00e8 climatizzata, mentre alcune sono fornite di ventilatore.<\/p>\n<\/div><\/section><br \/>\n<div  class='avia-button-wrap avia-button-center  avia-builder-el-10  el_after_av_textblock  avia-builder-el-last '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-aeorr-6ec858660dda3017b75bac7a5168e132\">\n#top #wrap_all .avia-button.av-aeorr-6ec858660dda3017b75bac7a5168e132:hover{\ncolor:white;\ntransition:all 0.4s ease-in-out;\n}\n<\/style>\n<a href='https:\/\/www.hotelliberty.top\/prenota' class='avia-color-theme-color avia-font-color-theme-color avia-button avia-button-fullwidth av-aeorr-6ec858660dda3017b75bac7a5168e132 avia-icon_select-yes-left-icon avia-color-theme-color'   aria-label=\"Prenota Adesso!\"><span class='avia_button_icon avia_button_icon_left' aria-hidden='true' data-av_icon='\ue85b' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >Prenota Adesso!<\/span><span class='avia_button_background avia-button avia-button-fullwidth avia-color-theme-color-subtle'><\/span><\/a><\/div><\/p><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-1121","post","type-post","status-publish","format-standard","hentry","category-hotel-sanremo-it"],"_links":{"self":[{"href":"https:\/\/www.hotelliberty.top\/it\/wp-json\/wp\/v2\/posts\/1121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotelliberty.top\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hotelliberty.top\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelliberty.top\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelliberty.top\/it\/wp-json\/wp\/v2\/comments?post=1121"}],"version-history":[{"count":4,"href":"https:\/\/www.hotelliberty.top\/it\/wp-json\/wp\/v2\/posts\/1121\/revisions"}],"predecessor-version":[{"id":1224,"href":"https:\/\/www.hotelliberty.top\/it\/wp-json\/wp\/v2\/posts\/1121\/revisions\/1224"}],"wp:attachment":[{"href":"https:\/\/www.hotelliberty.top\/it\/wp-json\/wp\/v2\/media?parent=1121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hotelliberty.top\/it\/wp-json\/wp\/v2\/categories?post=1121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hotelliberty.top\/it\/wp-json\/wp\/v2\/tags?post=1121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}